{"id":617,"date":"2020-09-09T12:02:23","date_gmt":"2020-09-09T10:02:23","guid":{"rendered":"https:\/\/eusec-culture-ngos.iti-germany.de\/?p=617"},"modified":"2020-09-09T12:09:28","modified_gmt":"2020-09-09T10:09:28","slug":"having-the-right-and-the-means-to-act-artistically-iaa-europe-talk-17-09-20-at-2pm","status":"publish","type":"post","link":"https:\/\/eusec-culture-ngos.iti-germany.de\/de\/2020\/09\/09\/having-the-right-and-the-means-to-act-artistically-iaa-europe-talk-17-09-20-at-2pm\/","title":{"rendered":"Having the right and the means to act artistically &#8211; Einladung digitaler IAA Europe Talk 17.09.20 14.00h"},"content":{"rendered":"<div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.igbk.de\/images\/news\/iaa_logo_sw_talks.jpg\" alt=\"iaa logo sw talks\" width=\"150\" height=\"125\" \/>Im Sp\u00e4tsommer 2020 startet die IAA Europe eine Reihe von \u00f6ffentlichen Online-Gespr\u00e4chen, <span class=\"ng-scope\">um Mitglieder und Unterst\u00fctzer*innen st\u00e4rker miteinander zu vernetzen und um die aktuelle Rolle von K\u00fcnstlervereinigungen und ihrer internationalen Zusammenarbeit zu diskutieren.<\/span><\/p>\n<p><!--more--><\/p>\n<hr \/>\n<blockquote><p>Herzliche Einladung zur Teilnahme am 17. September 2020 um 14.00h via <a href=\"https:\/\/us02web.zoom.us\/j\/81580283192?pwd=dzJGQzRwWFhnMmQ2b0JpdjVXTkxZZz09\">Zoom (link)<\/a>.<\/p><\/blockquote>\n<p><strong>&#8222;Having the right and the means to act artistically&#8220; | 17. September 2020, 14.00-15.30h<\/strong><\/p>\n<p>Begr\u00fc\u00dfung und Moderation: Andrea Kristek Kozarova (<a href=\"https:\/\/svu.sk\/en\/home\/\">SUVA \u2013 Slovak Union of Visual Artists<\/a>, Pr\u00e4sidentin der <a href=\"https:\/\/www.iaa-europe.eu\/index.php\">IAA Europe<\/a>)<\/p>\n<p>G\u00e4ste:<\/p>\n<ul>\n<li>Fabio Tolledi (Pr\u00e4sident des <a href=\"https:\/\/itiitaliancentre.wordpress.com\/\">Italian Centre of International Theatre Institute \u2013 ITI,<\/a> <span class=\"ng-scope\">Vizepr\u00e4sident f\u00fcr Europa im ITI Weltvorstand <\/span>und Sekret\u00e4r des <a href=\"https:\/\/www.iti-worldwide.org\/conflictzones.html\">Theater in Conflict Zones Network &#8211; TCZN<\/a>)<\/li>\n<li>Teemu M\u00e4ki (<a href=\"https:\/\/artists.fi\/\">Artists\u2019 Association of Finland<\/a>\/ Nationalkommittee der IAA in Finnland, Vorstandsmitglied IAA Europe)<\/li>\n<li>Marta Mabel Perez \/ angefragt \/ (Leitende Direktorin des Puerto Rico Museum of Art, <a href=\"https:\/\/www.apappr.org\/\">Asociaci\u00f3n Puertorrique\u00f1a De Artistas Pl\u00e1sticos<\/a>\/ Nationalkomitee der IAA in Puerto Rico, IAA Schatzmeisterin)<\/li>\n<\/ul>\n<p>Dem Gespr\u00e4ch folgt eine Frage-und-Antwort-Runde mit den Teilnehmer*innen.<\/p>\n<hr \/>\n<p>Die Corona-Pandemie 2020 hat die Welt in eine beispiellose Krise katapultiert, medizinisch, sozial und wirtschaftlich. Diese Situation hat auch den sozialen und wirtschaftlichen Status von K\u00fcnstler*innen und Kulturakteuren erheblich geschw\u00e4cht, die meist als Freiberufler*innen arbeiten oder als kleine Unternehmen aktiv sind und somit besonders anf\u00e4llig f\u00fcr wirtschaftliche Instabilit\u00e4t. Aber auch gr\u00f6\u00dfere Institutionen des Kultursektors leiden unter den Einschr\u00e4nkungen im \u00f6ffentlichen Leben und bef\u00fcrchten leicht einen Verlust staatlicher Unterst\u00fctzung, wenn der wirtschaftliche Druck in der politischen Entscheidungsfindung schwer wiegt.Wie k\u00f6nnen wir K\u00fcnstler*innen international unterst\u00fctzen und unser gemeinsames Wissen f\u00fcr eine erfolgreiche \u00d6ffentlichkeits- und Lobbyarbeit nutzen?<\/p>\n<p>Im Er\u00f6ffnungsgespr\u00e4ch im September 2020 berichten Fabio Tolledi, Marta Mabel Perez und Teemu M\u00e4ki beispielhaft aus den L\u00e4ndern Italien, Finnland und Puerto Rico, wie K\u00fcnstler*innen und Kunstinstitutionen derzeit mit der Krise umgehen, oder wie sie sich von dieser erholen. Wie verdienen K\u00fcnstler*innen in diesen L\u00e4ndern ihren Lebensunterhalt?<\/p>\n<p>Das Ph\u00e4nomen, dass viel Kunst und Kultur konsumiert wird, K\u00fcnstler*innen dabei\u00a0aber tendenziell wenig Verg\u00fctung f\u00fcr ihre Arbeit erhalten, gilt nicht erst seit der Corona-Pandemie. Die Pandemie hat das Problem nur verst\u00e4rkt.<\/p>\n<p>Welche Ma\u00dfnahmen ergreifen nationale Regierungen, um den Status von K\u00fcnstler*innen zu verbessern, und was kann im internationalen Austausch voneinander gelernt werden? Wie k\u00f6nnen die Grundlagen f\u00fcr Meinungs- und Kunstfreiheit gef\u00f6rdert werden: einerseits das Recht, zu sagen, was man denkt &#8211; aber andererseits auch die Mittel zu haben, dieses zu tun?<\/p>\n<p>Dieses Gespr\u00e4ch geht ebenfalls auf die Geschichte der International Association of Art (AIAP\/IAA) und des Internationalen Theaterinstituts (ITI) ein, beides K\u00fcnstlerverb\u00e4nde in offizieller Partnerschaft mit der UNESCO: Was ist ihre (gemeinsame) Strategie, was sind ihre aktuellen Aktivit\u00e4ten? Wie k\u00f6nnen wir uns zwischen den verschiedenen k\u00fcnstlerischen Sparten inspirieren lassen, wo k\u00f6nnen wir uns gegenseitig unterst\u00fctzen?<\/p>\n<hr \/>\n<p>Bitte beachten Sie, dass das Gespr\u00e4ch aufgezeichnet und f\u00fcr die \u00d6ffentlichkeitsarbeit online und in sozialen Medien genutzt wird. Wenn Sie nicht in der Aufnahme erscheinen wollen, bitte schalten Sie Ihr Mikrofon und Ihre Kamera w\u00e4hrend des Gespr\u00e4chs aus. Danke! Ein Tonsignal wird den Beginn der Aufnahme ank\u00fcndigen.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n<p><!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In the late summer of 2020, IAA Europe starts a series of online debates to bring members and supporters closer together, to discuss what can be the role of artists associations today and especially their (re)union on an international level.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,1],"tags":[],"class_list":["post-617","post","type-post","status-publish","format-standard","hentry","category-iaa-europe","category-uncategorized"],"translation":{"provider":"WPGlobus","version":"3.0.0","language":"de","enabled_languages":["en","de"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"de":{"title":true,"content":true,"excerpt":false}}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eusec-culture-ngos.iti-germany.de\/de\/wp-json\/wp\/v2\/posts\/617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eusec-culture-ngos.iti-germany.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eusec-culture-ngos.iti-germany.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eusec-culture-ngos.iti-germany.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/eusec-culture-ngos.iti-germany.de\/de\/wp-json\/wp\/v2\/comments?post=617"}],"version-history":[{"count":10,"href":"https:\/\/eusec-culture-ngos.iti-germany.de\/de\/wp-json\/wp\/v2\/posts\/617\/revisions"}],"predecessor-version":[{"id":643,"href":"https:\/\/eusec-culture-ngos.iti-germany.de\/de\/wp-json\/wp\/v2\/posts\/617\/revisions\/643"}],"wp:attachment":[{"href":"https:\/\/eusec-culture-ngos.iti-germany.de\/de\/wp-json\/wp\/v2\/media?parent=617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eusec-culture-ngos.iti-germany.de\/de\/wp-json\/wp\/v2\/categories?post=617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eusec-culture-ngos.iti-germany.de\/de\/wp-json\/wp\/v2\/tags?post=617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}